{"id":10251,"date":"2022-12-05T11:14:56","date_gmt":"2022-12-05T16:14:56","guid":{"rendered":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/?p=10251"},"modified":"2022-12-05T11:17:38","modified_gmt":"2022-12-05T16:17:38","slug":"congreso-diolee-2022","status":"publish","type":"post","link":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/noticias-de-interes\/congreso-diolee-2022\/","title":{"rendered":"Congreso DiOLEE 2022"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/media2.utp.edu.co\/programas\/23\/image.png\" alt=\"\" class=\"wp-image-10252\" srcset=\"https:\/\/media2.utp.edu.co\/programas\/23\/image.png 1024w, https:\/\/media2.utp.edu.co\/programas\/23\/image-300x240.png 300w, https:\/\/media2.utp.edu.co\/programas\/23\/image-768x614.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Desde hace algunos a\u00f1os el Grupo de Investigaci\u00f3n en Literatura Latinoamericana<br>y Ense\u00f1anza de la Literatura de la UTP, ha adelantado procesos relacionados con<br>la Did\u00e1ctica de la Oralidad, Lectura, Escritura y Escucha, a ra\u00edz de estos procesos,<br>surge el Congreso Nacional&nbsp;DiOLEE, que ha encontrado su espacio de desarrollo<br>en la Feria del Libro de Pereira, punto de encuentro que ha dado cabida a las<br>reflexiones y b\u00fasquedas no solamente del Grupo de Investigaci\u00f3n, sino tambi\u00e9n<br>de la comunidad educativa que comparte afinidades e intereses relacionadas con<br>estas \u00e1reas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En esta edici\u00f3n, el evento cont\u00f3 con el apoyo de la Vicerrector\u00eda de<br>Investigaciones, Innovaci\u00f3n y Extensi\u00f3n, el Departamento de Humanidades, los<br>posgrados en Literatura, la Maestr\u00eda en Estudios Culturales y Narrativas<br>Contempor\u00e1neas, el Programa de Acompa\u00f1amiento en Lectura y Escritura PALE-<br>UTP y el Semillero de Investigaci\u00f3n en Narrativas Contempor\u00e1neas, todos<br>articulados en el Grupo de Investigaci\u00f3n en Literatura Latinoamericana y<br>Ense\u00f1anza de la Literatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Durante los d\u00edas 5, 6 y 7 de octubre, en el marco de Paisaje, caf\u00e9 y libro \u2013 Feria<br>del libro del Eje Cafetero 2022, se llev\u00f3 a cabo el II Congreso nacional de<br>Did\u00e1ctica de la Oralidad, la Lectura, la Escritura y la Escucha. Se realizaron 15<br>actividades que contaron con la participaci\u00f3n de estudiantes de diversas<br>Instituciones Educativas de Risaralda, as\u00ed como de integrantes de la comunidad<br>educativa de la UTP, llegando a sumar un aproximado de 800 asistentes durante<br>los tres d\u00edas. Entre las actividades programadas, se cont\u00f3 con la intervenci\u00f3n de<br>talleristas y profesores locales, y de los invitados nacionales Juan Fernando<br>Merino, Fernando V\u00e1zquez Rodr\u00edguez y Celso Rom\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Agradecemos a toda la comunidad educativa por su participaci\u00f3n en este espacio,<br>y esperamos poder continuar ampliando los horizontes y di\u00e1logos sobre los temas<br>abordados en el congreso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde hace algunos a\u00f1os el Grupo de Investigaci\u00f3n en Literatura Latinoamericanay Ense\u00f1anza de la Literatura de la UTP, ha adelantado procesos relacionados conla Did\u00e1ctica de la Oralidad, Lectura, Escritura y [&#8230;]<\/p>\n","protected":false},"author":43,"featured_media":10252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-10251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-interes"],"_links":{"self":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/10251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/comments?post=10251"}],"version-history":[{"count":1,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/10251\/revisions"}],"predecessor-version":[{"id":10253,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/10251\/revisions\/10253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/media\/10252"}],"wp:attachment":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/media?parent=10251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/categories?post=10251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/tags?post=10251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}