{"id":34,"date":"2018-04-19T15:10:04","date_gmt":"2018-04-19T20:10:04","guid":{"rendered":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/2018\/04\/19\/resultados-de-aprendizaje\/"},"modified":"2025-03-21T10:21:05","modified_gmt":"2025-03-21T15:21:05","slug":"resultados-de-aprendizaje","status":"publish","type":"post","link":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/presentacion\/resultados-de-aprendizaje\/","title":{"rendered":"Resultados de Aprendizaje, PEP"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>El estudiante egresado podr\u00e1:<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Trabajar en campos interdisciplinarios con profesionales e investigadores de las artes y las humanidades.<\/li>\n\n\n\n<li>Desempe\u00f1arse como investigador, planificador, administrador y docente de planes y programas de la ense\u00f1anza de la literatura.<\/li>\n\n\n\n<li>Formular y asesorar programas de capacitaci\u00f3n especializada en la literatura para los docentes en instituciones educativas de la regi\u00f3n.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Expectativas ocupacionales del egresado<\/strong>:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El estudiante egresado tendr\u00e1 toda la formaci\u00f3n y competencias para desempe\u00f1arse como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asesor de programas de capacitaci\u00f3n para educadores, gestores culturales y especialistas en el campo de la literatura.<\/li>\n\n\n\n<li>Docente de literatura en todos los niveles de la Educaci\u00f3n Formal<\/li>\n\n\n\n<li>Investigador en las \u00e1reas de la literatura, en especial en literatura regional, colombiana y latinoamericana.<\/li>\n\n\n\n<li>Investigador y docente en programas de literatura en programas avanzados de posgrado.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Proyecto Educativo del Programa<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/drive.google.com\/file\/d\/1XDybX27-ClmfY7HAKKvs6E3GRFZD0KLs\/view?usp=sharing\" data-type=\"link\" data-id=\"https:\/\/drive.google.com\/file\/d\/1XDybX27-ClmfY7HAKKvs6E3GRFZD0KLs\/view?usp=sharing\">Da click aqu\u00ed para acceder al documento del PEP<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estudiante egresado podr\u00e1: Expectativas ocupacionales del egresado: El estudiante egresado tendr\u00e1 toda la formaci\u00f3n y competencias para desempe\u00f1arse como: Proyecto Educativo del Programa Da click aqu\u00ed para acceder al [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-34","post","type-post","status-publish","format-standard","hentry","category-presentacion"],"_links":{"self":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":17,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/34\/revisions"}],"predecessor-version":[{"id":10326,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/34\/revisions\/10326"}],"wp:attachment":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/media?parent=34"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/categories?post=34"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/tags?post=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}