{"id":36,"date":"2018-04-19T15:15:19","date_gmt":"2018-04-19T20:15:19","guid":{"rendered":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/2018\/04\/19\/contenidos-tematicos\/"},"modified":"2018-04-19T15:15:19","modified_gmt":"2018-04-19T20:15:19","slug":"contenidos-tematicos","status":"publish","type":"post","link":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/sin-categoria\/contenidos-tematicos\/","title":{"rendered":"Contenidos Tem\u00e1ticos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Primer eje. Formaci\u00f3n ciudadana: referido a la capacidad del estudiante de asumir los retos que ata\u00f1en a su profesi\u00f3n, relacionando el hacer diario con la reflexi\u00f3n que posibilitan las lecturas literarias y filos\u00f3ficas. La Maestr\u00eda no es solo un espacio para la consecuci\u00f3n de unos saberes espec\u00edficos, sino tambi\u00e9n para la puesta en pr\u00e1ctica y la incidencia de los mismos en la cotidianidad de sus estudiantes. Se busca incidir positivamente en los estudiantes de la Maestr\u00eda en sus formas de ver y pensar el mundo, as\u00ed como en sus maneras de actuar y asumir la sociedad y la cultura.<br>\nSegundo eje: Formaci\u00f3n como investigador: busca el mejoramiento y la apropiaci\u00f3n de las herramientas b\u00e1sicas para que el estudiante asuma procesos de investigaci\u00f3n. Se postulan diferentes lineamientos que ordenan y enriquecen la reflexi\u00f3n te\u00f3rica sobre el fen\u00f3meno literario. Este eje se encuentra enfocado en unos \u00e1mbitos espec\u00edficos: literatura latinoamericana, colombiana, con particular inter\u00e9s en los procesos literarios de la regi\u00f3n.<br>\nTercer eje. Complementariedad en el ejercicio docente: la Maestr\u00eda aporta herramientas did\u00e1cticas y conceptuales para un mejor ejercicio de la labor docente, tanto en instituciones de educaci\u00f3n media como de educaci\u00f3n superior. Uno de los principales aportes al estudiante es el ordenamiento y claridad conceptual en cuanto a g\u00e9neros literarios y autores, tanto como la capacidad de entrever la complejidad de los mismos en relaci\u00f3n con la sociedad y la cultura, de manera que se supere el tradicional esquema de ense\u00f1anza de la literatura, donde suelen presentarse formas y momentos hist\u00f3ricos descontextualizados, vistos \u00fanicamente desde el resumen y la enumeraci\u00f3n de personajes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c1reas 1 2 3 4 Acceso y teor\u00eda <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Taller de Acercamiento a la Poes\u00eda<\/li><li>Taller de Acercamiento a la narrativa<\/li><li>Taller de Acercamiento a la dramaturgia Profundizaci\u00f3n e investigaci\u00f3n<\/li><li>Seminario de investigaci\u00f3n I<\/li><li>Seminario de investigaci\u00f3n II Interdisciplinar Literatura y<\/li><li>Filosof\u00eda I<\/li><li>Literatura y Filosof\u00eda II<\/li><li>Seminario de investigaci\u00f3n III Modernidad y postmodernidad Estudios monogr\u00e1ficos<\/li><li>C\u00e1tedra de autores (Poes\u00eda)<\/li><li>C\u00e1tedra de autores Narrativa I<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00e1tedra de autores Narrativa II Trabajo investigativo y tutor\u00eda<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Metodolog\u00eda de la investigaci\u00f3n literaria<\/li><li>Proyecto de investigaci\u00f3n I<\/li><li>Proyecto de investigaci\u00f3n II<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Primer eje. Formaci\u00f3n ciudadana: referido a la capacidad del estudiante de asumir los retos que ata\u00f1en a su profesi\u00f3n, relacionando el hacer diario con la reflexi\u00f3n que posibilitan las lecturas [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-36","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":1,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/36\/revisions"}],"predecessor-version":[{"id":10021,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/posts\/36\/revisions\/10021"}],"wp:attachment":[{"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/media?parent=36"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/categories?post=36"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-en-literatura\/wp-json\/wp\/v2\/tags?post=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}