{"id":6,"date":"2018-04-23T15:57:24","date_gmt":"2018-04-23T20:57:24","guid":{"rendered":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/2018\/04\/23\/historia\/"},"modified":"2022-09-09T10:44:29","modified_gmt":"2022-09-09T15:44:29","slug":"historia","status":"publish","type":"post","link":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/sin-categoria\/historia\/","title":{"rendered":"Historia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/media2.utp.edu.co\/programas\/21\/historia.png\" alt=\"historia\" width=\"300\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Renovaci\u00f3n del Registro Calificado mediante la Resoluci\u00f3n 01277 del Ministerio de Educaci\u00f3n Nacional<br>Programa de posgrado en proceso de autoevaluaci\u00f3n con fines de Acreditaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra Maestri\u0301a en Este\u0301tica y Creacio\u0301n es un programa de posgrado en la modalidad de investigacio\u0301n, fundamentada en el marco de expansio\u0301n de las este\u0301ticas, en dia\u0301logo con las diferentes tendencias de la cri\u0301tica y la historia del arte en sus desarrollos actuales, los estudios culturales y el desplazamiento del campo del arte al mundo de la cultura y la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desarrollamos una concepcio\u0301n de creacio\u0301n en la que el campo arti\u0301stico y los modos de produccio\u0301n de obra configuren procesos culturales, intersubjetivos, colaborativos y\/o de competencias, en los que el artista se reconoce como un productor &#8211; agenciador de proyectos creativos. Adem\u00e1s, configuramos nuevas relaciones entre teori\u0301a y praxis, con e\u0301nfasis en la investigacio\u0301n, la creacio\u0301n de obra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renovaci\u00f3n del Registro Calificado mediante la Resoluci\u00f3n 01277 del Ministerio de Educaci\u00f3n NacionalPrograma de posgrado en proceso de autoevaluaci\u00f3n con fines de Acreditaci\u00f3n. Nuestra Maestri\u0301a en Este\u0301tica y Creacio\u0301n es [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/posts\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":2,"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/posts\/6\/revisions"}],"predecessor-version":[{"id":10180,"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/posts\/6\/revisions\/10180"}],"wp:attachment":[{"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/media?parent=6"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/categories?post=6"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artes.utp.edu.co\/maestria-estetica-y-creacion\/wp-json\/wp\/v2\/tags?post=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}